{"id":321,"date":"2024-01-03T12:00:11","date_gmt":"2024-01-03T12:00:11","guid":{"rendered":"https:\/\/ocean-pure.wh56.host-rack.com\/?page_id=321"},"modified":"2024-12-10T15:25:57","modified_gmt":"2024-12-10T15:25:57","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.oceanpure-solutions.ch\/en\/datenschutz\/","title":{"rendered":"datenschutz"},"content":{"rendered":"<div class=\"shariff shariff-align-flex-start shariff-widget-align-flex-start\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.oceanpure-solutions.ch%2Fen%2Fdatenschutz%2F%20datenschutz\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.oceanpure-solutions.ch%2Fen%2Fdatenschutz%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.oceanpure-solutions.ch%2Fen%2Fdatenschutz%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.oceanpure-solutions.ch%2Fen%2Fdatenschutz%2F&text=datenschutz\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><\/ul><\/div><section class=\"bde-section-321-187 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-321-188 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-video-321-189 bde-video\">\n<div class=\"ee-video-container\">\n                                                                            \n                                \n                <iframe\n                        class=\"ee-video\"\n                title=\"\"\n                                src=\"https:\/\/www.youtube-nocookie.com\/embed\/6F5A2elw61g?feature=oembed&controls=0&autoplay=1&mute=1&modestbranding=1&start=5&rel=0&playlist=6F5A2elw61g&loop=1&enablejsapi=1\"\n                frameborder=\"0\"\n                allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\"\n                allowfullscreen>\n                <\/iframe>\n                    \n        \n            \n    <\/div>\n\n<\/div>\n<\/div><div class=\"bde-rich-text-321-190 bde-rich-text breakdance-rich-text-styles\">\n<svg class=\"waves\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"\nviewbox=\"0 24 150 28\" preserveaspectratio=\"none\" shape-rendering=\"auto\">\n<defs>\n<path id=\"gentle-wave\" d=\"M-160 44c30 0 58-18 88-18s 58 18 88 18 58-18 88-18 58 18 88 18 v44h-352z\" \/>\n<\/defs>\n<g class=\"parallax\">\n<use xlink:href=\"#gentle-wave\" x=\"48\" y=\"0\" fill=\"rgba(255,255,255,0.7\" \/>\n<use xlink:href=\"#gentle-wave\" x=\"48\" y=\"3\" fill=\"rgba(255,255,255,0.5)\" \/>\n<use xlink:href=\"#gentle-wave\" x=\"48\" y=\"5\" fill=\"rgba(255,255,255,0.3)\" \/>\n<use xlink:href=\"#gentle-wave\" x=\"48\" y=\"7\" fill=\"#fff\" \/>\n<\/g>\n<\/svg>\n<\/div><\/div>\n<\/section><section class=\"bde-section-321-104 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-321-105 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-321-106 bde-text\">\nOcean Pure Solutions\n<\/div><h1 class=\"bde-heading-321-107 bde-heading\">\nDatenschutzerkl\u00e4rung\n<\/h1><div class=\"bde-div-321-108 bde-div\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-321-109 bde-heading\">\n1. Ein \u00dcberblick \u00fcber den Datenschutz\n<\/h1><div class=\"bde-rich-text-321-110 bde-rich-text breakdance-rich-text-styles\">\n<h3>Allgemeine Hinweise<\/h3><p>Die nachfolgenden Informationen bieten einen klaren \u00dcberblick dar\u00fcber, wie mit Ihren personenbezogenen Daten umgegangen wird, wenn Sie diese Website besuchen. Personenbezogene Daten umfassen s\u00e4mtliche Informationen, die zur pers\u00f6nlichen Identifikation genutzt werden k\u00f6nnen. Detaillierte Angaben zum Datenschutz finden Sie in unserer Datenschutzerkl\u00e4rung, die unter diesem Text aufgef\u00fchrt ist.<\/p><p>Sofern Sie uns personenbezogene Daten von anderen Personen (z. B. Familienmitglieder, Daten von Arbeitskollegen) zur Verf\u00fcgung stellen, bitten wir Sie sicherzustellen, dass diese Personen \u00fcber die vorliegende Datenschutzerkl\u00e4rung informiert sind. Bitte teilen Sie uns ihre personenbezogenen Daten nur dann mit, wenn Sie dazu berechtigt sind und die Angaben korrekt sind.<\/p>\n<\/div><div class=\"bde-rich-text-321-137 bde-rich-text breakdance-rich-text-styles\">\n<h3>Wer tr\u00e4gt die Verantwortung f\u00fcr die Datenerfassung auf dieser Webseite?<\/h3><p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n<\/div><div class=\"bde-rich-text-321-138 bde-rich-text breakdance-rich-text-styles\">\n<h3>Wie erfassen wir Ihre Daten?<\/h3><p>Ihre Daten werden einerseits dadurch erfasst, dass Sie sie aktiv mitteilen, beispielsweise indem Sie Informationen in ein Kontaktformular eingeben.<\/p><p>Andererseits erfolgt die automatische Erfassung oder nach Ihrer Zustimmung w\u00e4hrend des Besuchs der Website durch unsere IT-Systeme. Hierbei handelt es sich insbesondere um technische Daten (wie beispielsweise Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten. Weitere Informationen dazu finden Sie auch im Abschnitt 4 \"Datenerfassung auf dieser Website\".<\/p>\n<\/div><div class=\"bde-rich-text-321-139 bde-rich-text breakdance-rich-text-styles\">\n<h3>Wozu verwenden wir Ihre Daten?<\/h3><p>Die Erhebung von Daten erfolgt zu dem Zweck, der zum Zeitpunkt der Erhebung angegeben wurde. Beispielsweise k\u00f6nnen Daten erhoben werden, um Ihren Newsletter zu abonnieren, Ihre Anfragen zu beantworten, Ihre Teilnahme an Petitionen, Kampagnen oder Aktionen zu verarbeiten oder Ihre Spenden, Mitgliedschaft oder Eink\u00e4ufe im OceanPure Solution-Shop abzuwickeln.<\/p><p>Einige Daten werden erfasst, um eine fehlerfreie Bereitstellung der Webseite sicherzustellen. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<\/div><div class=\"bde-rich-text-321-140 bde-rich-text breakdance-rich-text-styles\">\n<h3>Welche Rechte stehen Ihnen im Zusammenhang mit Ihren Daten zu?<\/h3><p>Wir haben angemessene technische und organisatorische Sicherheitsma\u00dfnahmen getroffen, um Ihre personenbezogenen Daten vor unbefugtem Zugriff und Missbrauch zu sch\u00fctzen. Dazu geh\u00f6ren IT- und Netzwerksicherheitsl\u00f6sungen, Zugangskontrollen und -beschr\u00e4nkungen, Verschl\u00fcsselung von Datentr\u00e4gern und \u00dcbermittlungen sowie regelm\u00e4\u00dfige Kontrollen.<\/p><p>Sie haben jederzeit das Recht, kostenlos Auskunft \u00fcber die Herkunft, Empf\u00e4nger und den Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Zudem haben Sie das Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Falls Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Des Weiteren steht Ihnen unter bestimmten Umst\u00e4nden das Recht zu, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Schlie\u00dflich haben Sie das Recht, sich bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu beschweren.<\/p><p>F\u00fcr weitere Fragen zum Datenschutz oder um Ihre Rechte geltend zu machen, k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<\/div><div class=\"bde-rich-text-321-141 bde-rich-text breakdance-rich-text-styles\">\n<h3>Analyse-Tools und Tools von Dritt\u00adanbietern<\/h3><p>Beim Besuch dieser Website besteht die M\u00f6glichkeit, dass Ihr Surfverhalten statistisch ausgewertet wird, insbesondere mithilfe von sogenannten Analyseprogrammen.<\/p><p>Weitere Einzelheiten zu diesen Analyseprogrammen finden Sie in unserer ausf\u00fchrlichen Datenschutzerkl\u00e4rung.<\/p>\n<\/div><h1 class=\"bde-heading-321-142 bde-heading\">\n2. Hosting\n<\/h1><div class=\"bde-rich-text-321-143 bde-rich-text breakdance-rich-text-styles\">\n<p>Wir nutzen die Dienste des folgenden Anbieters zum Hosting unserer Website:<\/p>\n<\/div><div class=\"bde-rich-text-321-144 bde-rich-text breakdance-rich-text-styles\">\n<h3>Externes Hosting<\/h3><p>Diese Website wird extern gehostet. Die erfassten personenbezogenen Daten auf dieser Website werden auf den Servern des Hosting-Anbieters gespeichert. Hierzu k\u00f6nnen unter anderem IP-Adressen, Kontaktanfragen, Meta- und Kommunikationsdaten, Vertragsdaten, Kontaktdaten, Namen, Websitezugriffe sowie weitere Daten, die durch die Nutzung der Website generiert werden, geh\u00f6ren.<\/p><p>Das externe Hosting erfolgt zum Zweck der Vertragserf\u00fcllung gegen\u00fcber potenziellen und bestehenden Kunden (Art. 6 Abs. 1 lit. b DSGVO) und im Interesse einer sicheren, schnellen und effizienten Bereitstellung unseres Online-Angebots durch einen professionellen Anbieter (Art. 6 Abs. 1 lit. f DSGVO). Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z. B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p><p>Unser Hosting-Partner wird Ihre Daten nur in dem Umfang verarbeiten, der zur Erf\u00fcllung seiner Leistungspflichten erforderlich ist und unseren Weisungen hinsichtlich dieser Daten folgen. <br><br>Wir setzen folgende(n) Hoster ein: [Name des Hosting-Anbieters].<br><br>Kontaktadresse vom Hoster: <\/p>\n<\/div><h1 class=\"bde-heading-321-145 bde-heading\">\n3.  \u00dcbersicht zum Datenschutz\n<\/h1><div class=\"bde-rich-text-321-146 bde-rich-text breakdance-rich-text-styles\">\n<h3>Privacy policy<\/h3><p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p><p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p><p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<\/div><div class=\"bde-rich-text-321-147 bde-rich-text breakdance-rich-text-styles\">\n<h3>Hinweis zur verantwortlichen Stelle<\/h3><p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p><p>Verein Ocean Pure Solutions<br>Dorfstrasse 40 <br>CH-6026 Rain<\/p><p>Telefon: +41 (0)  <br>E-Mail: <a target=\"_self\" href=\"mailto:hallo@oceanpure-solutions.ch\">hallo@oceanpure-solutions.ch<\/a><\/p><p>Die verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z. B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<\/div><div class=\"bde-rich-text-321-148 bde-rich-text breakdance-rich-text-styles\">\n<h3>Speicherdauer<\/h3><p>Sofern in dieser Datenschutzerkl\u00e4rung keine spezifischere Speicherdauer genannt wurde, bleiben Ihre personenbezogenen Daten bei uns gespeichert, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Im Falle eines berechtigten L\u00f6schersuchens oder des Widerrufs einer Einwilligung zur Datenverarbeitung erfolgt die L\u00f6schung Ihrer Daten, sofern keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten vorliegen (z. B. gesetzliche Aufbewahrungs- und Dokumentationspflichten). In letzterem Fall erfolgt die L\u00f6schung nach dem Wegfall dieser Gr\u00fcnde.<\/p><p>Es ist jedoch m\u00f6glich, dass personenbezogene Daten f\u00fcr die Zeit aufbewahrt werden, in der Anspr\u00fcche gegen unser Unternehmen geltend gemacht werden k\u00f6nnen oder soweit wir anderweitig gesetzlich dazu verpflichtet sind oder berechtigte Gesch\u00e4ftsinteressen dies erfordern (z.B. f\u00fcr Beweis- und Dokumentationszwecke). Sobald Ihre personenbezogenen Daten f\u00fcr die oben genannten Zwecke nicht mehr erforderlich sind, werden sie grunds\u00e4tzlich und soweit m\u00f6glich gel\u00f6scht oder anonymisiert. F\u00fcr betriebliche Daten (z.B. Systemprotokolle, Logs) gelten in der Regel k\u00fcrzere Aufbewahrungsfristen von zw\u00f6lf Monaten oder weniger.<\/p>\n<\/div><div class=\"bde-rich-text-321-149 bde-rich-text breakdance-rich-text-styles\">\n<h3>Allgemeine Informationen zu den rechtlichen Grundlagen der Datenverarbeitung auf dieser Website:<\/h3><p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Im Falle einer ausdr\u00fccklichen Einwilligung in die \u00dcbertragung personenbezogener Daten in Drittstaaten erfolgt die Datenverarbeitung ausserdem auf Grundlage von Art. 49 Abs. 1 lit. a DSGVO. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihr Endger\u00e4t (z. B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus\u00e4tzlich auf Grundlage von \u00a7 25 Abs. 1 TTDSG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung vorvertraglicher Massnahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. \u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n<\/div><div class=\"bde-rich-text-321-150 bde-rich-text breakdance-rich-text-styles\">\n<h3>Datenschutz\u00adbeauftragter<\/h3>\n<\/div><div class=\"bde-rich-text-321-151 bde-rich-text breakdance-rich-text-styles\">\n<h3>Hinweis zur Datenweitergabe in die USA und sonstige Drittstaaten<\/h3><p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in den USA oder sonstigen datenschutzrechtlich nicht sicheren Drittstaaten. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Drittstaaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in diesen L\u00e4ndern kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann. Beispielsweise sind US-Unternehmen dazu verpflichtet, personenbezogene Daten an Sicherheitsbeh\u00f6rden herauszugeben, ohne dass Sie als Betroffener hiergegen gerichtlich vorgehen k\u00f6nnten. Es kann daher nicht ausgeschlossen werden, dass US-Beh\u00f6rden (z.&nbsp;B. Geheimdienste) Ihre auf US-Servern befindlichen Daten zu \u00dcberwachungszwecken verarbeiten, auswerten und dauerhaft speichern. Wir haben auf diese Verarbeitungst\u00e4tigkeiten keinen Einfluss.<\/p><p>Befindet sich ein Empf\u00e4nger in einem Land ohne angemessenen gesetzlichen Datenschutz, verpflichten wir den Empf\u00e4nger vertraglich zur Einhaltung des anwendbaren Datenschutzes (dazu<br>verwenden wir die revidierten Standardvertragsklauseln der Europ\u00e4ischen Kommission, die hier:<br><a href=\"https:\/\/eurlex.europa.eu\/eli\/dec_impl\/2021\/914\/oj\">https:\/\/eurlex.europa.eu\/eli\/dec_impl\/2021\/914\/oj<\/a>? abrufbar sind), soweit er nicht bereits einem gesetzlich anerkannten Regelwerk zur Sicherstellung des Datenschutzes unterliegt und wir uns nicht auf eine Ausnahmebestimmung st\u00fctzen k\u00f6nnen. Eine Ausnahme kann namentlich bei Rechtsverfahren im Ausland gelten, aber auch in F\u00e4llen \u00fcberwiegender \u00f6ffentlicher Interessen oder wenn eine Vertragsabwicklung eine solche Bekanntgabe erfordert, wenn Sie eingewilligt haben oder wenn es sich um von Ihnen allgemein zug\u00e4nglich gemachte Daten handelt, deren<br>Bearbeitung Sie nicht widersprochen haben.<\/p>\n<\/div><div class=\"bde-rich-text-321-152 bde-rich-text breakdance-rich-text-styles\">\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3><p>Bestimmte Datenverarbeitungsvorg\u00e4nge sind ohne Einwilligung erlaubt. Wenn Sie der Verarbeitung nicht zustimmen m\u00f6chten, haben Sie jederzeit das Recht, ohne Angabe von Gr\u00fcnden dagegen zu widersprechen (siehe dazu den vorgeschlagenen Abschnitt \"Rechte der betroffenen Person\"). Andere Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer Einwilligung erlaubt. Falls Sie uns Ihre Einwilligung zur Verarbeitung Ihrer personenbezogenen Daten f\u00fcr bestimmte Zwecke erteilt haben, erfolgt die Verarbeitung im Rahmen und auf Basis dieser Einwilligung, sofern wir keine andere Rechtsgrundlage haben und diese erforderlich ist. Eine erteilte Einwilligung kann jederzeit widerrufen werden, jedoch hat dies keine Auswirkungen auf bereits durchgef\u00fchrte Datenverarbeitungen.<\/p>\n<\/div><div class=\"bde-rich-text-321-153 bde-rich-text breakdance-rich-text-styles\">\n<h3>Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3><p>Im Falle von Verst\u00f6ssen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutmasslichen Verstosses zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p><p>In der Schweiz hat jede betroffene Person hat \u00fcberdies das Recht, ihre Anspr\u00fcche gerichtlich durchzusetzen oder bei der zust\u00e4ndigen Datenschutzbeh\u00f6rde eine Beschwerde einzureichen. Die zust\u00e4ndige Datenschutzbeh\u00f6rde der Schweiz ist der Eidgen\u00f6ssische Datenschutz- und \u00d6ffentlichkeitsbeauftragte<br>(<a href=\"http:\/\/www.edoeb.admin.ch\">http:\/\/www.edoeb.admin.ch<\/a>).<\/p>\n<\/div><div class=\"bde-rich-text-321-154 bde-rich-text breakdance-rich-text-styles\">\n<h3>Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3><p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<\/div><div class=\"bde-rich-text-321-155 bde-rich-text breakdance-rich-text-styles\">\n<h3>Auskunft, L\u00f6schung und Berichtigung<\/h3><p>Sie haben das Recht auf Auskunft, ggf. Berichtigung, L\u00f6schung, das Recht auf Einschr\u00e4nkung der Datenbearbeitung insbesondere jener f\u00fcr genannte Zwecke betriebenen Profilings und weiterer berechtigter Interessen an der Bearbeitung. Bitte beachten Sie aber, dass wir uns vorbehalten, unsererseits die gesetzlich vorgesehenen Einschr\u00e4nkungen geltend zu machen, etwa wenn wir zur Aufbewahrung oder Bearbeitung gewisser Daten verpflichtet sind, daran ein \u00fcberwiegendes Interesse haben (soweit wir uns darauf berufen d\u00fcrfen) oder sie f\u00fcr die Geltendmachung von Anspr\u00fcchen ben\u00f6tigen. Falls f\u00fcr Sie Kosten anfallen, werden wir Sie vorab informieren. Die Aus\u00fcbung solcher Rechte setzt in der Regel voraus, dass Sie Ihre Identit\u00e4t eindeutig nachweisen (z.B. durch eine Ausweiskopie, wo Ihre Identit\u00e4t sonst nicht klar ist bzw. verifiziert werden kann). Zur Geltendmachung Ihrer Rechte k\u00f6nnen Sie uns unter der in Ziffer 3 angegebenen Adresse kontaktieren.<\/p>\n<\/div><div class=\"bde-rich-text-321-156 bde-rich-text breakdance-rich-text-styles\">\n<h3>Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3><p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Bitte nehmen Sie hierzu jederzeit Kontakt mit uns auf. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p><ul><li><p>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><li><p>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4ssig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/p><\/li><li><p>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><li><p>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><\/ul><p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 abgesehen von ihrer Speicherung \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n<\/div><div class=\"bde-rich-text-321-157 bde-rich-text breakdance-rich-text-styles\">\n<h3>SSL- bzw. TLS-Verschl\u00fcsselung<\/h3><p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Bitte nehmen Sie hierzu jederzeit Kontakt mit uns auf. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p><ul><li><p>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><li><p>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4ssig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/p><\/li><li><p>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><li><p>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p><\/li><\/ul><p>Aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Informationen, wie beispielsweise Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, wird auf dieser Seite eine SSL- bzw. TLS-Verschl\u00fcsselung verwendet. Eine verschl\u00fcsselte Verbindung ist erkennbar daran, dass sich die Adresszeile Ihres Browsers von \"http:\/\/\" zu \"https:\/\/\" \u00e4ndert und ein Schloss-Symbol in Ihrer Browserzeile erscheint.<\/p><p>Durch die Aktivierung der SSL- bzw. TLS-Verschl\u00fcsselung k\u00f6nnen die von Ihnen \u00fcbermittelten Daten nicht von Dritten mitgelesen werden.<\/p>\n<\/div><div class=\"bde-rich-text-321-158 bde-rich-text breakdance-rich-text-styles\">\n<h3>Verschl\u00fcsselter Zahlungsverkehr auf dieser Website<\/h3><p>Nach dem Abschluss eines kostenpflichtigen Vertrags besteht, sofern erforderlich, die Verpflichtung, uns Ihre Zahlungsdaten (z. B. Kontonummer bei Einzugserm\u00e4chtigung) zur Verf\u00fcgung zu stellen, um die Zahlungsabwicklung zu erm\u00f6glichen.<\/p><p>Der Zahlungsverkehr \u00fcber die g\u00e4ngigen Zahlungsmittel (Visa\/MasterCard, Lastschriftverfahren) erfolgt ausschlie\u00dflich \u00fcber eine verschl\u00fcsselte SSL- bzw. TLS-Verbindung. Eine verschl\u00fcsselte Verbindung ist daran erkennbar, dass sich die Adresszeile des Browsers von \"http:\/\/\" zu \"https:\/\/\" \u00e4ndert und ein Schloss-Symbol in Ihrer Browserzeile erscheint.<\/p><p>Durch die Verwendung verschl\u00fcsselter Kommunikation k\u00f6nnen Ihre Zahlungsdaten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<\/div><div class=\"bde-rich-text-321-159 bde-rich-text breakdance-rich-text-styles\">\n<h3>Widerspruch gegen Werbe-E-Mails<\/h3><p>Hiermit wird der Nutzung der im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien widersprochen. Die Betreiber dieser Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<\/div><div class=\"bde-rich-text-321-160 bde-rich-text breakdance-rich-text-styles\">\n<h3>Widerspruch gegen Werbe-E-Mails<\/h3><p>Hiermit wird der Nutzung der im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien widersprochen. Die Betreiber dieser Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<\/div><h1 class=\"bde-heading-321-161 bde-heading\">\n4. Datenerfassung auf dieser Website\n<\/h1><div class=\"bde-rich-text-321-162 bde-rich-text breakdance-rich-text-styles\">\n<h3>Cookies<\/h3><p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Datenpakete und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen&nbsp;oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p><p>Teilweise k\u00f6nnen auch Cookies von Drittunternehmen auf Ihrem Endger\u00e4t gespeichert werden, wenn Sie unsere Seite betreten (Third-Party-Cookies). Diese erm\u00f6glichen uns oder Ihnen die Nutzung bestimmter Dienstleistungen des Drittunternehmens (z.&nbsp;B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p><p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Websitefunktionen ohne diese nicht funktionieren w\u00fcrden (z.&nbsp;B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies dienen dazu, das Nutzerverhalten auszuwerten&nbsp;oder Werbung anzuzeigen.<\/p><p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.&nbsp;B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z.&nbsp;B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschliesslich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG); die Einwilligung ist jederzeit widerrufbar.<\/p><p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschliessen sowie das automatische L\u00f6schen der Cookies beim Schliessen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p><p>Soweit Cookies von Drittunternehmen oder zu Analysezwecken eingesetzt werden, werden wir Sie hier\u00fcber im Rahmen dieser Datenschutzerkl\u00e4rung gesondert informieren und soweit erforderlich eine Einwilligung abfragen (Cookie-Banner).<\/p>\n<\/div><div class=\"bde-rich-text-321-163 bde-rich-text breakdance-rich-text-styles\">\n<h3>Einwilligung mit Borlabs Cookie<\/h3><p>Unsere Website nutzt die Consent-Technologie von Borlabs Cookie, um Ihre Einwilligung zur Speicherung bestimmter Cookies in Ihrem Browser oder zum Einsatz bestimmter Technologien einzuholen und diese datenschutzkonform zu dokumentieren. Anbieter dieser Technologie ist die Borlabs GmbH, R\u00fcbenkamp 32, 22305 Hamburg (im Folgenden Borlabs).<\/p><p>Wenn Sie unsere Website betreten, wird ein Borlabs-Cookie in Ihrem Browser gespeichert, in dem die von Ihnen erteilten Einwilligungen oder der Widerruf dieser Einwilligungen gespeichert werden. Diese Daten werden nicht an den Anbieter von Borlabs Cookie weitergegeben.<\/p><p>Die erfassten Daten werden gespeichert, bis Sie uns zur L\u00f6schung auffordern bzw. das Borlabs-Cookie selbst l\u00f6schen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt. Zwingende gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt. Details zur Datenverarbeitung von Borlabs Cookie finden Sie unter&nbsp;<a href=\"https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/\"><u>https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/<\/u><\/a>.<\/p><p>Der Einsatz der Borlabs-Cookie-Consent-Technologie erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f\u00fcr den Einsatz von Cookies einzuholen. Rechtsgrundlage hierf\u00fcr ist Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<\/div><div class=\"bde-rich-text-321-164 bde-rich-text breakdance-rich-text-styles\">\n<h3>Server-Log-Dateien<\/h3><p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p><ul><li><p>Browsertyp und Browserversion<\/p><\/li><li><p>verwendetes Betriebssystem<\/p><\/li><li><p>Referrer URL<\/p><\/li><li><p>Hostname des zugreifenden Rechners<\/p><\/li><li><p>Uhrzeit der Serveranfrage<\/p><\/li><li><p>IP-Adresse<\/p><\/li><\/ul><p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p><p>Die Erfassung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Website \u2013 hierzu m\u00fcssen die Server-Log-Files erfasst werden.<\/p>\n<\/div><div class=\"bde-rich-text-321-165 bde-rich-text breakdance-rich-text-styles\">\n<h3>Kontaktformular<\/h3><p>Wenn Sie uns Anfragen \u00fcber das Kontaktformular senden, werden die Angaben aus dem Anfrageformular einschlie\u00dflich der von Ihnen dort angegebenen Kontaktdaten bei uns gespeichert. Dies dient der Bearbeitung der Anfrage und m\u00f6glichen Anschlussfragen. Wir geben diese Daten ohne Ihre Einwilligung nicht weiter.<\/p><p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen anderen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO), sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p><p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<\/div><div class=\"bde-rich-text-321-170 bde-rich-text breakdance-rich-text-styles\">\n<h3>Anfrage per E-Mail, Telefon oder Telefax<\/h3><p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, werden Ihre Anfrage sowie alle damit verbundenen personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten werden ohne Ihre Einwilligung nicht an Dritte weitergegeben.<\/p><p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen anderen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO), sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p><p>Die von Ihnen an uns \u00fcbermittelten Daten im Rahmen von Kontaktanfragen verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<\/div><div class=\"bde-rich-text-321-167 bde-rich-text breakdance-rich-text-styles\">\n<h3>Kommunikation via WhatsApp<\/h3><p>F\u00fcr die Kommunikation mit unseren Kunden und sonstigen Dritten nutzen wir unter anderem den Instant-Messaging-Dienst WhatsApp. Anbieter ist die WhatsApp Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland.<\/p><p>Die Kommunikation erfolgt \u00fcber eine Ende-zu-Ende-Verschl\u00fcsselung (Peer-to-Peer), die verhindert, dass WhatsApp oder sonstige Dritte Zugriff auf die Kommunikationsinhalte erlangen k\u00f6nnen. WhatsApp erh\u00e4lt jedoch Zugriff auf Metadaten, die im Zuge des Kommunikationsvorgangs entstehen (z.&nbsp;B. Absender, Empf\u00e4nger und Zeitpunkt). Wir weisen ferner darauf hin, dass WhatsApp nach eigener Aussage, personenbezogene Daten seiner Nutzer mit seiner in den USA ans\u00e4ssigen Konzernmutter Meta teilt. Weitere Details zur Datenverarbeitung finden Sie in der Datenschutzrichtlinie von WhatsApp unter:&nbsp;<a href=\"https:\/\/www.whatsapp.com\/legal\/#privacy-policy\"><u>https:\/\/www.whatsapp.com\/legal\/#privacy-policy<\/u><\/a>.<\/p><p>Der Einsatz von WhatsApp erfolgt auf Grundlage unseres berechtigten Interesses an einer m\u00f6glichst schnellen und effektiven Kommunikation mit Kunden, Interessenten und sonstigen Gesch\u00e4fts- und Vertragspartnern (Art. 6 Abs. 1 lit. f DSGVO). Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Datenverarbeitung ausschliesslich auf Grundlage der Einwilligung; diese ist jederzeit mit Wirkung f\u00fcr die Zukunft widerrufbar.<\/p><p>Die zwischen und auf WhatsApp ausgetauschten Kommunikationsinhalte verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p><p>Wir nutzen WhatsApp in der Variante \u201eWhatsApp Business\u201c.<\/p><p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:&nbsp;<a href=\"https:\/\/www.whatsapp.com\/legal\/business-data-transfer-addendum\"><u>https:\/\/www.whatsapp.com\/legal\/business-data-transfer-addendum<\/u><\/a>.<\/p><p>Wir haben unsere WhatsApp-Accounts so eingestellt, dass es keinen automatischen Datenabgleich mit dem Adressbuch auf den im Einsatz befindlichen Smartphones macht.<\/p><p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) mit dem oben genannten Anbieter geschlossen.<\/p>\n<\/div><h1 class=\"bde-heading-321-171 bde-heading\">\n5. Soziale Medien\n<\/h1><div class=\"bde-rich-text-321-166 bde-rich-text breakdance-rich-text-styles\">\n<h3>Social-Media-Elemente mit Shariff<\/h3><p>Auf dieser Website werden Elemente von sozialen Medien verwendet (z.&nbsp;B. Facebook, Twitter, Instagram, Pinterest, XING, LinkedIn, Tumblr).<\/p><p>Die Social-Media-Elemente k\u00f6nnen Sie in der Regel anhand der jeweiligen Social-Media-Logos erkennen. Um den Datenschutz auf dieser Website zu gew\u00e4hrleisten, verwenden wir diese Elemente nur zusammen mit der sogenannten \u201eShariff\u201c-L\u00f6sung. Diese Anwendung verhindert, dass die auf dieser Website integrierten Social-Media-Elemente Ihre personenbezogenen Daten schon beim ersten Betreten der Seite an den jeweiligen Anbieter \u00fcbertragen.<\/p><p>Erst wenn Sie das jeweilige Social-Media-Element durch Anklicken der zugeh\u00f6rigen Schaltfl\u00e4che aktivieren, wird eine direkte Verbindung zum Server des Anbieters hergestellt (Einwilligung). Sobald Sie das Social-Media-Element aktivieren, erh\u00e4lt der jeweilige Anbieter die Information, dass Sie mit Ihrer IP-Adresse diese Website besucht haben. Wenn Sie gleichzeitig in Ihrem jeweiligen Social-Media-Account (z.&nbsp;B. Facebook) eingeloggt sind, kann der jeweilige Anbieter den Besuch dieser Website Ihrem Benutzerkonto zuordnen.<\/p><p>Das Aktivieren des Plugins stellt eine Einwilligung im Sinne des Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG dar. Diese Einwilligung k\u00f6nnen Sie jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen.<\/p><p>Der Einsatz des Dienstes erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f\u00fcr den Einsatz bestimmter Technologien einzuholen. Rechtsgrundlage hierf\u00fcr ist Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<\/div><h1 class=\"bde-heading-321-175 bde-heading\">\n6. Werbung und Analyse-Tools\n<\/h1><div class=\"bde-rich-text-321-176 bde-rich-text breakdance-rich-text-styles\">\n<h3>Google Analytics<\/h3><p>Google Analytics ist ein Webanalysedienst von Google Ireland Ltd, Irland und Google Inc., USA (\u201eGoogle\u201c). Google Analytics verwendet Cookies. Die durch die Cookies erzeugten Informationen \u00fcber die Benutzung dieser Webseite (einschliesslich Ihrer IP-Adresse) werden an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um die Nutzung der Webseite durch Sie auszuwerten, um Reports \u00fcber die Webseitenaktivit\u00e4ten f\u00fcr die Webseitenbetreiber zusammenzustellen und um weitere mit der Webseitennutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben ist oder soweit Dritte diese Daten im Auftrag von Google verarbeiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten von Google in Verbindung bringen.<\/p><p>Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung der Browser Software verhindern; wir weisen Sie jedoch darauf hin, dass in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen unserer Website vollumf\u00e4nglich genutzt werden k\u00f6nnen. Durch die Nutzung unserer Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<\/p><p>Wir verwenden den Dienst \u201eGoogle Tag Manager\u201c von Google. Der Google Tag Manager ist ein Hilfsdienst und verarbeitet selbst personenbezogene Daten nur zu technisch notwendigen Zwecken. Der Google Tag Manager sorgt f\u00fcr das Laden anderer Komponenten, die ihrerseits unter Umst\u00e4nden Daten erfassen, greift aber nicht auf diese Daten zu. Weitere Informationen zum Google Tag Manager finden Sie in den&nbsp;<a target=\"_blank\" rel=\"noopener nofollow\" href=\"https:\/\/policies.google.com\/privacy?hl=de\"><u>Datenschutzbestimmungen von Google<\/u><\/a>. Durch die Nutzung unserer Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<\/p><p>Innerhalb von Google Analytics verwenden wir die Funktion \u201eGoogle Signals\u201c. Google Signals sind Sitzungsdaten von Websites und Apps, welche Google mit Usern verkn\u00fcpft, die in ihrem Google-Konto angemeldet sind und personalisierte Werbung erlaubt haben. Seitenbetreiber k\u00f6nnen mit diesen Daten das Verhalten potenzieller Kunden \u00fcber verschiedene Ger\u00e4te hinweg verfolgen.<\/p>\n<\/div><div class=\"bde-rich-text-321-173 bde-rich-text breakdance-rich-text-styles\">\n<h3>Facebook Pixel und Facebook Conversion API<\/h3><p>Diese Website nutzt zur Konversionsmessung den Besucheraktions-Pixel von Facebook und die Facebook Conversion API. Anbieter dieser Dienste ist die Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland. Die erfassten Daten werden nach Aussage von Facebook jedoch auch in die USA und in andere Drittl\u00e4nder \u00fcbertragen.<\/p><p>Mit dem Facebook Pixel kann das Verhalten der Seitenbesucher nachverfolgt werden, nachdem diese durch Klick auf eine Facebook-Werbeanzeige auf die Website des Anbieters weitergeleitet wurden. Dadurch k\u00f6nnen die Wirksamkeit der Facebook-Werbeanzeigen f\u00fcr statistische und Marktforschungszwecke ausgewertet werden und zuk\u00fcnftige Werbemassnahmen optimiert werden.<\/p><p>Die Facebook Conversion API ist eine Datenschnittstelle, \u00fcber die wir Daten \u00fcber Ihr Verhalten auf unserer Website an Facebook zur Auswertung \u00fcbermitteln. Dadurch k\u00f6nnen wir Ihnen Werbeanzeigen passend zu Ihrem Nutzerverhalten auf unserer Website anzeigen lassen. Im Zusammenhang mit der Conversion API verwenden wir folgende Daten: E-Mail-Adresse, Telefonnummer, Geschlecht, Geburtsdatum, Vor- und Nachname, Adressdaten, IP-Adresse, verwendeter Browser, verwendetes Betriebssystem.<\/p><p>Die erhobenen Daten sind f\u00fcr uns als Betreiber dieser Website anonym, wir k\u00f6nnen keine R\u00fcckschl\u00fcsse auf die Identit\u00e4t der Nutzer ziehen. Die Daten werden aber von Facebook gespeichert und verarbeitet, sodass eine Verbindung zum jeweiligen Nutzerprofil m\u00f6glich ist und Facebook die Daten f\u00fcr eigene Werbezwecke, entsprechend der&nbsp;<a target=\"_blank\" rel=\"nofollow noopener\" href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\"><u>Facebook-Datenverwendungsrichtlinie<\/u><\/a>&nbsp;verwenden kann. Dadurch kann Facebook das Schalten von Werbeanzeigen auf Seiten von Facebook sowie ausserhalb von Facebook erm\u00f6glichen. Diese Verwendung der Daten kann von uns als Seitenbetreiber nicht beeinflusst werden.<\/p><p>Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG. Die Einwilligung ist jederzeit widerrufbar.<\/p><p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:&nbsp;<a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\"><u>https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/u><\/a>&nbsp;und&nbsp;<a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\"><u>https:\/\/de-de.facebook.com\/help\/566994660333381<\/u><\/a>.<\/p><p>Soweit mit Hilfe des hier beschriebenen Tools personenbezogene Daten auf unserer Website erfasst und an Facebook weitergeleitet werden, sind wir und die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland gemeinsam f\u00fcr diese Datenverarbeitung verantwortlich (Art. 26 DSGVO). Die gemeinsame Verantwortlichkeit beschr\u00e4nkt sich dabei ausschliesslich auf die Erfassung der Daten und deren Weitergabe an Facebook. Die nach der Weiterleitung erfolgende Verarbeitung durch Facebook ist nicht Teil der gemeinsamen Verantwortung. Die uns gemeinsam obliegenden Verpflichtungen wurden in einer Vereinbarung \u00fcber gemeinsame Verarbeitung festgehalten. Den Wortlaut der Vereinbarung finden Sie unter:&nbsp;<a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\"><u>https:\/\/www.facebook.com\/legal\/controller_addendum<\/u><\/a>. Laut dieser Vereinbarung sind wir f\u00fcr die Erteilung der Datenschutzinformationen beim Einsatz des Facebook-Tools und f\u00fcr die datenschutzrechtlich sichere Implementierung des Tools auf unserer Website verantwortlich. F\u00fcr die Datensicherheit der Facebook-Produkte ist Facebook verantwortlich. Betroffenenrechte (z.&nbsp;B. Auskunftsersuchen) hinsichtlich der bei Facebook verarbeiteten Daten k\u00f6nnen Sie direkt bei Facebook geltend machen. Wenn Sie die Betroffenenrechte bei uns geltend machen, sind wir verpflichtet, diese an Facebook weiterzuleiten.<\/p><p>In den Datenschutzhinweisen von Facebook finden Sie weitere Hinweise zum Schutz Ihrer Privatsph\u00e4re:&nbsp;<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\"><u>https:\/\/de-de.facebook.com\/about\/privacy\/<\/u><\/a>.<\/p><p>Sie k\u00f6nnen ausserdem die Remarketing-Funktion \u201eCustom Audiences\u201c im Bereich Einstellungen f\u00fcr Werbeanzeigen unter&nbsp;<a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screendeaktivieren\"><u>https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/u>deaktivieren<\/a>. Dazu m\u00fcssen Sie bei Facebook angemeldet sein.<\/p><p>Wenn Sie kein Facebook Konto besitzen, k\u00f6nnen Sie nutzungsbasierte Werbung von Facebook auf der Website der European Interactive Digital Advertising Alliance deaktivieren:&nbsp;<a href=\"http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/\"><u>http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/<\/u><\/a>.<\/p>\n<\/div><h1 class=\"bde-heading-321-169 bde-heading\">\n7. Newsletter\n<\/h1><div class=\"bde-rich-text-321-172 bde-rich-text breakdance-rich-text-styles\">\n<h3>Newsletter<\/h3><p>Wenn Sie unseren angebotenen Newsletter abonnieren m\u00f6chten, ben\u00f6tigen wir von Ihnen Ihre E-Mail-Adresse sowie Informationen, die es uns erm\u00f6glichen zu \u00fcberpr\u00fcfen, ob Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden entweder nicht erhoben oder nur auf freiwilliger Basis. Die Abwicklung des Newsletter-Versands erfolgt \u00fcber Newsletterdiensteanbieter, die im Folgenden n\u00e4her beschrieben werden.<\/p>\n<\/div><h1 class=\"bde-heading-321-179 bde-heading\">\n8. Plugins und Tools\n<\/h1><div class=\"bde-rich-text-321-177 bde-rich-text breakdance-rich-text-styles\">\n<h3>YouTube mit erweitertem Datenschutz<\/h3><p>Diese Website bindet Videos der Website YouTube ein. Betreiber der Seiten ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p><p>Wir nutzen YouTube im erweiterten Datenschutzmodus. Dieser Modus bewirkt laut YouTube, dass YouTube keine Informationen \u00fcber die Besucher auf dieser Website speichert, bevor diese sich das Video ansehen. Die Weitergabe von Daten an YouTube-Partner wird durch den erweiterten Datenschutzmodus hingegen nicht zwingend ausgeschlossen. So stellt YouTube \u2013 unabh\u00e4ngig davon, ob Sie sich ein Video ansehen \u2013 eine Verbindung zum Google DoubleClick-Netzwerk her.<\/p><p>Sobald Sie ein YouTube-Video auf dieser Website starten, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Wenn Sie in Ihrem YouTube-Account eingeloggt sind, erm\u00f6glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p><p>Des Weiteren kann YouTube nach Starten eines Videos verschiedene Cookies auf Ihrem Endger\u00e4t speichern oder vergleichbare Wiedererkennungstechnologien (z.&nbsp;B. Device-Fingerprinting) einsetzen. Auf diese Weise kann YouTube Informationen \u00fcber Besucher dieser Website erhalten. Diese Informationen werden u.&nbsp;a. verwendet, um Videostatistiken zu erfassen, die Anwenderfreundlichkeit zu verbessern und Betrugsversuchen vorzubeugen.<\/p><p>Gegebenenfalls k\u00f6nnen nach dem Start eines YouTube-Videos weitere Datenverarbeitungsvorg\u00e4nge ausgel\u00f6st werden, auf die wir keinen Einfluss haben.<\/p><p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschliesslich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p><p>Weitere Informationen \u00fcber Datenschutz bei YouTube finden Sie in deren Datenschutzerkl\u00e4rung unter:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\"><u>https:\/\/policies.google.com\/privacy?hl=de<\/u><\/a>.<\/p>\n<\/div><h1 class=\"bde-heading-321-178 bde-heading\">\n9. Spenden\n<\/h1><div class=\"bde-rich-text-321-180 bde-rich-text breakdance-rich-text-styles\">\n<p>Wenn Sie eine Spende \u00fcber unsere Website t\u00e4tigen, werden personenbezogene Daten erfasst, um die Transaktion abzuwickeln und Ihnen eine Spendenbescheinigung ausstellen zu k\u00f6nnen.<\/p>\n<\/div><div class=\"bde-rich-text-321-186 bde-rich-text breakdance-rich-text-styles\">\n<h3>Verwendete Spendenplattformen<\/h3><p>F\u00fcr die Entgegennahme von Spenden nutzen wir das Give-Spenden-Plugin, eine Erweiterung f\u00fcr WordPress, die von der <a href=\"http:\/\/Impress.org\">Impress.org<\/a>, LLC bereitgestellt wird. Um Spenden \u00fcber das Give-Spenden-Plugin zu erm\u00f6glichen, werden personenbezogene Daten wie Ihr Name, Ihre E-Mail-Adresse und Zahlungsinformationen (z.B. Kreditkartennummer, Bankverbindung) ben\u00f6tigt. Die Verarbeitung Ihrer Daten erfolgt ausschlie\u00dflich zum Zweck der Spendenabwicklung und zur Gew\u00e4hrleistung der Sicherheit und Integrit\u00e4t des Zahlungsvorgangs. Die Rechtsgrundlage f\u00fcr die Verarbeitung Ihrer Daten im Zusammenhang mit Spenden \u00fcber das Give-Spenden-Plugin ergibt sich aus Art. 6 Abs. 1 lit. b DSGVO (Erf\u00fcllung eines Vertrags) und ggf. Art. 6 Abs. 1 lit. f DSGVO (berechtigtes Interesse an der Sicherstellung der Spendenabwicklung). Die Daten werden f\u00fcr die Dauer der Spendenabwicklung und im Rahmen der gesetzlichen Aufbewahrungsfristen gespeichert. Weitere Informationen zur Datenschutzpraxis des Give-Spenden-Plugins finden Sie in der Datenschutzerkl\u00e4rung von Give. Beachten Sie, dass Sie durch die Nutzung des Give-Spenden-Plugins auch den Nutzungsbedingungen von Give zustimmen.<\/p><h3><br>Daten, die \u00fcbermittelt werden k\u00f6nnen:<\/h3><ul><li><p>Name und Kontaktdaten des Spenders<\/p><\/li><li><p>Zahlungsinformationen (z.B. Kreditkartennummer, Bankverbindung)<\/p><\/li><li><p>Betrag der Spende<\/p><\/li><\/ul><h3><br>Zweck der Daten\u00fcbermittlung:<\/h3><p>Die \u00dcbermittlung der Daten an Spendenplattformen erfolgt zum Zwecke der Abwicklung von Spenden, der Ausstellung von Spendenbescheinigungen und ggf. der Kommunikation mit dem Spender.<\/p><h3><br>Rechtsgrundlage:<\/h3><p>Die Rechtsgrundlage f\u00fcr die Daten\u00fcbermittlung an Spendenplattformen ergibt sich aus Art. 6 Abs. 1 lit. b DSGVO (Erf\u00fcllung eines Vertrags) und ggf. Art. 6 Abs. 1 lit. c DSGVO (Erf\u00fcllung gesetzlicher Verpflichtungen, z. B. Ausstellung von Spendenbescheinigungen).<\/p><h3><br>Speicherdauer:<\/h3><p>Die Daten werden f\u00fcr die Dauer der Spendenabwicklung gespeichert und anschlie\u00dfend gem\u00e4\u00df den gesetzlichen Aufbewahrungsfristen archiviert.<\/p>\n<\/div><h1 class=\"bde-heading-321-184 bde-heading\">\n10. Online-Shop Zahlungs\u00adanbieter\n<\/h1><div class=\"bde-rich-text-321-185 bde-rich-text breakdance-rich-text-styles\">\n<h3>Verarbeiten von Kunden- und Vertragsdaten<\/h3><p>Wir  erheben, verarbeiten und verwenden personenbezogene Kunden- und Vertragsdaten, um unsere Vertragsbeziehungen zu begr\u00fcnden, inhaltlich zu gestalten und zu \u00e4ndern. Personenbezogene Daten \u00fcber die Nutzung dieser Website (Nutzungsdaten) werden nur erhoben, verarbeitet und genutzt, soweit dies erforderlich ist, um dem Nutzer die Inanspruchnahme des Dienstes zu erm\u00f6glichen oder abzurechnen. Die Rechtsgrundlage hierf\u00fcr ist Art. 6 Abs. 1 lit. b DSGVO.<\/p><p>Die erfassten Kundendaten werden nach Abschluss des Auftrags oder Beendigung der Gesch\u00e4ftsbeziehung und nach Ablauf der ggf. bestehenden gesetzlichen Aufbewahrungsfristen gel\u00f6scht. Gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n<\/div><div class=\"bde-rich-text-321-181 bde-rich-text breakdance-rich-text-styles\">\n<h3>Daten\u00fcbertragung im Rahmen von Vertragsabschl\u00fcssen f\u00fcr Online-Shops, H\u00e4ndler und den Versand von Waren<\/h3><p>Die \u00dcbermittlung von Daten bei Vertragsschluss f\u00fcr Online-Shops, H\u00e4ndler und Warenversand erfolgt gem\u00e4\u00df den datenschutzrechtlichen Bestimmungen. Dazu geh\u00f6ren insbesondere die \u00dcbermittlung von personenbezogenen Daten wie Name, Adresse, Zahlungsinformationen und sonstige f\u00fcr die Abwicklung des Vertrags notwendige Informationen. Diese Daten\u00fcbermittlung dient dem Zweck der Vertragserf\u00fcllung und erm\u00f6glicht es dem Online-Shop, die bestellten Waren an den Kunden zu versenden.<\/p><p>Die Rechtsgrundlage f\u00fcr die Daten\u00fcbermittlung bei Vertragsschluss ist in der Regel Art. 6 Abs. 1 lit. b der Datenschutzgrundverordnung (DSGVO), da die Verarbeitung der Daten f\u00fcr die Erf\u00fcllung eines Vertrags oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. Es ist wichtig, dass Online-Shops transparent \u00fcber die Daten\u00fcbermittlung informieren und sicherstellen, dass angemessene Sicherheitsma\u00dfnahmen getroffen werden, um die Integrit\u00e4t und Vertraulichkeit der \u00fcbermittelten Daten zu gew\u00e4hrleisten.<\/p>\n<\/div><div class=\"bde-rich-text-321-182 bde-rich-text breakdance-rich-text-styles\">\n<h3>Zahlungsdienste<\/h3><p>Wir binden Zahlungsdienste von Drittunternehmen auf unserer Website ein. Wenn Sie einen Kauf bei uns t\u00e4tigen, werden Ihre Zahlungsdaten (z.&nbsp;B. Name, Zahlungssumme, Kontoverbindung, Kreditkartennummer) vom Zahlungsdienstleister zum Zwecke der Zahlungsabwicklung verarbeitet. F\u00fcr diese Transaktionen gelten die jeweiligen Vertrags- und Datenschutzbestimmungen der jeweiligen Anbieter. Der Einsatz der Zahlungsdienstleister erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO (Vertragsabwicklung) sowie im Interesse eines m\u00f6glichst reibungslosen, komfortablen und sicheren Zahlungsvorgangs (Art. 6 Abs. 1 lit. f DSGVO). Soweit f\u00fcr bestimmte Handlungen Ihre Einwilligung abgefragt wird, ist Art. 6 Abs. 1 lit. a DSGVO Rechtsgrundlage der Datenverarbeitung; Einwilligungen sind jederzeit f\u00fcr die Zukunft widerrufbar.<\/p><p>Folgende Zahlungsdienste \/ Zahlungsdienstleister setzen wir im Rahmen dieser Website ein:<\/p>\n<\/div><div class=\"bde-rich-text-321-183 bde-rich-text breakdance-rich-text-styles\">\n<h3>PayPal<\/h3><p>F\u00fcr die Abwicklung von Zahlungen verwenden wir den Online-Zahlungsdienst PayPal. Die PayPal-Zahlungsplattform wird bereitgestellt von der PayPal (Europe) S.\u00e0 r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxembourg (im Folgenden \"PayPal\").<\/p><p>Um Zahlungen \u00fcber PayPal abwickeln zu k\u00f6nnen, werden personenbezogene Daten wie Ihr Name, Ihre Adresse, Ihre E-Mail-Adresse und Zahlungsinformationen (z.B. Kreditkartennummer, Bankverbindung) ben\u00f6tigt. Die Verarbeitung Ihrer Daten erfolgt ausschlie\u00dflich zum Zweck der Zahlungsabwicklung und zur Gew\u00e4hrleistung der Sicherheit und Integrit\u00e4t des Zahlungsvorgangs.<\/p><p>Die Rechtsgrundlage f\u00fcr die Verarbeitung Ihrer Daten im Zusammenhang mit Zahlungen \u00fcber PayPal ergibt sich aus Art. 6 Abs. 1 lit. b DSGVO (Erf\u00fcllung eines Vertrags) und ggf. Art. 6 Abs. 1 lit. f DSGVO (berechtigtes Interesse an der Sicherstellung der Zahlungsabwicklung).<\/p><p>Die Daten werden f\u00fcr die Dauer der Zahlungsabwicklung und im Rahmen der gesetzlichen Aufbewahrungsfristen gespeichert.<\/p><p>Weitere Informationen zur Datenschutzpraxis von PayPal finden Sie in der Datenschutzerkl\u00e4rung von PayPal.<\/p><p>Bitte beachten Sie, dass Sie durch die Nutzung von PayPal auch den Nutzungsbedingungen von PayPal zustimmen.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Ocean Pure Solutions Datenschutzerkl\u00e4rung 1. Ein \u00dcberblick \u00fcber den Datenschutz Allgemeine HinweiseDie nachfolgenden Informationen bieten einen klaren \u00dcberblick dar\u00fcber, wie mit Ihren personenbezogenen Daten umgegangen wird, wenn Sie diese Website besuchen. Personenbezogene Daten umfassen s\u00e4mtliche Informationen, die zur pers\u00f6nlichen Identifikation genutzt werden k\u00f6nnen. Detaillierte Angaben zum Datenschutz finden Sie in unserer Datenschutzerkl\u00e4rung, die unter diesem [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-321","page","type-page","status-publish","hentry"],"campaignId":"","_links":{"self":[{"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/pages\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":0,"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oceanpure-solutions.ch\/en\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}